{"id":28105,"date":"2026-07-15T12:33:49","date_gmt":"2026-07-15T10:33:49","guid":{"rendered":"https:\/\/extremebarcelona.com\/?p=28105"},"modified":"2026-07-15T12:33:49","modified_gmt":"2026-07-15T10:33:49","slug":"extreme-barcelona-estrena-mundial-hors-class-uci","status":"publish","type":"post","link":"https:\/\/extremebarcelona.com\/ca\/2026\/07\/15\/extreme-barcelona-estrena-mundial-hors-class-uci\/","title":{"rendered":"Extreme Barcelona far\u00e0 hist\u00f2ria amb l&#8217;estrena mundial del nou segell Hors Class de la UCI"},"content":{"rendered":"<div class=\"et_pb_module et_pb_text et_pb_text_0  et_pb_text_align_left et_pb_bg_layout_light\">\n<div class=\"et_pb_text_inner\">\n<ul>\n<li>\n<p data-path-to-node=\"22\"><b data-path-to-node=\"22\" data-index-in-node=\"0\">L&#8217;esdeveniment barcelon\u00ed ser\u00e0 el primer del m\u00f3n a acollir la 2a m\u00e0xima categoria de la Uni\u00f3 Ciclista Internacional en BMX Freestyle del 4 al 6 de setembre.<\/b><\/p>\n<p data-path-to-node=\"23\">L&#8217;Extreme Barcelona es convertir\u00e0 en el primer esdeveniment del planeta a estrenar el prestigi\u00f3s segell <b data-path-to-node=\"23\" data-index-in-node=\"104\">Hors Class (HC)<\/b> de la Uni\u00f3 Ciclista Internacional (UCI). La cita, que enguany celebra el seu <b data-path-to-node=\"23\" data-index-in-node=\"197\">18\u00e8 aniversari<\/b>, marcar\u00e0 una fita hist\u00f2rica en la seva pr\u00f2xima edici\u00f3, que es disputar\u00e0 del 4 al 6 de setembre, en incorporar aquesta nova categoria dissenyada per ordenar i classificar les competicions dins del calendari internacional, atorgant un estatus superior a les proves m\u00e9s destacades de BMX Freestyle.<\/p>\n<h4 data-path-to-node=\"24\"><strong>Un reconeixement a l&#8217;excel\u00b7l\u00e8ncia esportiva<\/strong><\/h4>\n<p data-path-to-node=\"25\">El segell Hors Class forma part de l&#8217;estructura de la UCI per identificar aquelles proves del circuit internacional que compleixen amb els est\u00e0ndards m\u00e9s exigents a nivell organitzatiu, esportiu i de posicionament. Amb aquest reconeixement, l&#8217;Extreme Barcelona es consolida com el referent global per inaugurar aquesta categoria, posicionant el BMX Freestyle com una disciplina clau dins del ciclisme d&#8217;acci\u00f3 impulsat per la federaci\u00f3 internacional.<\/p>\n<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<div class=\"et_pb_module et_pb_image et_pb_image_0\"><span class=\"et_pb_image_wrap \"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-28078\" title=\"HORS_UCI-01 (1)\" src=\"https:\/\/extremebarcelona.com\/wp-content\/uploads\/2026\/07\/HORS_UCI-01-1-scaled.jpg\" sizes=\"(max-width: 2048px) 100vw, 2048px\" srcset=\"https:\/\/extremebarcelona.com\/wp-content\/uploads\/2026\/07\/HORS_UCI-01-1-scaled.jpg 2048w, https:\/\/extremebarcelona.com\/wp-content\/uploads\/2026\/07\/HORS_UCI-01-1-240x300.jpg 240w, https:\/\/extremebarcelona.com\/wp-content\/uploads\/2026\/07\/HORS_UCI-01-1-819x1024.jpg 819w, https:\/\/extremebarcelona.com\/wp-content\/uploads\/2026\/07\/HORS_UCI-01-1-768x960.jpg 768w, https:\/\/extremebarcelona.com\/wp-content\/uploads\/2026\/07\/HORS_UCI-01-1-1229x1536.jpg 1229w, https:\/\/extremebarcelona.com\/wp-content\/uploads\/2026\/07\/HORS_UCI-01-1-1639x2048.jpg 1639w, https:\/\/extremebarcelona.com\/wp-content\/uploads\/2026\/07\/HORS_UCI-01-1-1080x1350.jpg 1080w, https:\/\/extremebarcelona.com\/wp-content\/uploads\/2026\/07\/HORS_UCI-01-1-1280x1600.jpg 1280w, https:\/\/extremebarcelona.com\/wp-content\/uploads\/2026\/07\/HORS_UCI-01-1-980x1225.jpg 980w, https:\/\/extremebarcelona.com\/wp-content\/uploads\/2026\/07\/HORS_UCI-01-1-480x600.jpg 480w\" alt=\"\" width=\"2048\" height=\"2560\" \/><\/span><\/div>\n<div class=\"et_pb_module et_pb_text et_pb_text_1  et_pb_text_align_left et_pb_bg_layout_light\">\n<div class=\"et_pb_text_inner\">\n<h4 data-path-to-node=\"26\"><strong>Esport d&#8217;elit i cultura urbana al Parc del F\u00f2rum<\/strong><\/h4>\n<p data-path-to-node=\"27\">L&#8217;Extreme Barcelona \u00e9s un esdeveniment multiesportiu plenament consolidat que fusiona l&#8217;adrenalina de les disciplines d&#8217;acci\u00f3 amb un vibrant ambient festiu i cultural. M\u00e9s enll\u00e0 del BMX Freestyle, el programa comptar\u00e0 con competicions d&#8217;alt nivell en les modalitats de <b data-path-to-node=\"27\" data-index-in-node=\"269\">Skateboarding, Scooter Freestyle, Breaking i B\u00e0squet 3&#215;3<\/b>.<\/p>\n<p data-path-to-node=\"28\">El seu format combina competicions oficials on riders internacionals es disputaran els punts del r\u00e0nquing mundial, juntament amb exhibicions i activitats paral\u00b7leles obertes al p\u00fablic. Aquesta barreja de t\u00e8cnica i espectacularitat convertir\u00e0 el Parc del F\u00f2rum en l&#8217;epicentre de la de l&#8217;escena urbana internacional durant tres dies.<\/p>\n<h4 data-path-to-node=\"29\"><strong>Creixement internacional: Urban World Series<\/strong><\/h4>\n<p data-path-to-node=\"30\">L&#8217;esdeveniment reunir\u00e0 esportistes d&#8217;arreu del m\u00f3n i es mant\u00e9 com una parada fonamental dins del circuit <b data-path-to-node=\"30\" data-index-in-node=\"105\">Urban World Series<\/b>, que compta amb seus en pa\u00efsos com Mal\u00e0isia, Portugal o Fran\u00e7a. Aquesta edici\u00f3 especial, marcada per l&#8217;estrena del segell de la UCI, reafirma el creixement exponencial dels esports urbans i el paper protagonista de Barcelona en el panorama global.<\/p>\n<\/div>\n<\/div>\n<div class=\"et_pb_module et_pb_image et_pb_image_1\"><\/div>\n<div class=\"et_pb_module et_pb_image et_pb_image_2\"><span class=\"et_pb_image_wrap \"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-28084\" title=\"\" src=\"https:\/\/extremebarcelona.com\/wp-content\/uploads\/2026\/07\/@raimonrg_EXT25_-men-uci-final-25-scaled.jpg\" sizes=\"(max-width: 2560px) 100vw, 2560px\" srcset=\"https:\/\/extremebarcelona.com\/wp-content\/uploads\/2026\/07\/@raimonrg_EXT25_-men-uci-final-25-scaled.jpg 2560w, https:\/\/extremebarcelona.com\/wp-content\/uploads\/2026\/07\/@raimonrg_EXT25_-men-uci-final-25-300x200.jpg 300w, https:\/\/extremebarcelona.com\/wp-content\/uploads\/2026\/07\/@raimonrg_EXT25_-men-uci-final-25-1024x683.jpg 1024w, https:\/\/extremebarcelona.com\/wp-content\/uploads\/2026\/07\/@raimonrg_EXT25_-men-uci-final-25-768x512.jpg 768w, https:\/\/extremebarcelona.com\/wp-content\/uploads\/2026\/07\/@raimonrg_EXT25_-men-uci-final-25-1536x1024.jpg 1536w, https:\/\/extremebarcelona.com\/wp-content\/uploads\/2026\/07\/@raimonrg_EXT25_-men-uci-final-25-2048x1366.jpg 2048w, https:\/\/extremebarcelona.com\/wp-content\/uploads\/2026\/07\/@raimonrg_EXT25_-men-uci-final-25-1080x720.jpg 1080w, https:\/\/extremebarcelona.com\/wp-content\/uploads\/2026\/07\/@raimonrg_EXT25_-men-uci-final-25-1280x854.jpg 1280w, https:\/\/extremebarcelona.com\/wp-content\/uploads\/2026\/07\/@raimonrg_EXT25_-men-uci-final-25-980x653.jpg 980w, https:\/\/extremebarcelona.com\/wp-content\/uploads\/2026\/07\/@raimonrg_EXT25_-men-uci-final-25-480x320.jpg 480w\" alt=\"\" width=\"2560\" height=\"1707\" \/><\/span><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Amb motiu del seu 18\u00e8 aniversari, l&#8217;Extreme Barcelona marca una fita hist\u00f2rica en esdevenir la primera parada mundial amb la m\u00e0xima distinci\u00f3 de la Uni\u00f3 Ciclista Internacional (UCI) en BMX Freestyle.<\/p>\n","protected":false},"author":15,"featured_media":28082,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[20],"tags":[975,944,93,109,976,185,220],"class_list":["post-28105","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticies","tag-975","tag-944","tag-barcelona-ca","tag-bmx-ca","tag-bnx","tag-extreme-ca","tag-urban"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Extreme Barcelona far\u00e0 hist\u00f2ria amb l&#039;estrena mundial del nou segell Hors Class de la UCI - Extreme Barcelona<\/title>\n<meta name=\"description\" content=\"L&#039;Extreme Barcelona ser\u00e0 el primer esdeveniment del m\u00f3n a estrenar el prestigi\u00f3s segell Hors Class de la UCI per al BMX Freestyle del 4 al 6 de setembre.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/extremebarcelona.com\/ca\/2026\/07\/15\/extreme-barcelona-estrena-mundial-hors-class-uci\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Extreme Barcelona far\u00e0 hist\u00f2ria amb l&#039;estrena mundial del nou segell Hors Class de la UCI - Extreme Barcelona\" \/>\n<meta property=\"og:description\" content=\"L&#039;Extreme Barcelona ser\u00e0 el primer esdeveniment del m\u00f3n a estrenar el prestigi\u00f3s segell Hors Class de la UCI per al BMX Freestyle del 4 al 6 de setembre.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/extremebarcelona.com\/ca\/2026\/07\/15\/extreme-barcelona-estrena-mundial-hors-class-uci\/\" \/>\n<meta property=\"og:site_name\" content=\"Extreme Barcelona\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T10:33:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/extremebarcelona.com\/wp-content\/uploads\/2026\/07\/@raimonrg_EXT25_-uci-women-final-2-3-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cristian Dedeu Van den Berg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cristian Dedeu Van den Berg\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/extremebarcelona.com\\\/ca\\\/2026\\\/07\\\/15\\\/extreme-barcelona-estrena-mundial-hors-class-uci\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/extremebarcelona.com\\\/ca\\\/2026\\\/07\\\/15\\\/extreme-barcelona-estrena-mundial-hors-class-uci\\\/\"},\"author\":{\"name\":\"Cristian Dedeu Van den Berg\",\"@id\":\"https:\\\/\\\/extremebarcelona.com\\\/#\\\/schema\\\/person\\\/0ab8e57dd9880fb0b11f077d9f23c4aa\"},\"headline\":\"Extreme Barcelona far\u00e0 hist\u00f2ria amb l&#8217;estrena mundial del nou segell Hors Class de la UCI\",\"datePublished\":\"2026-07-15T10:33:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/extremebarcelona.com\\\/ca\\\/2026\\\/07\\\/15\\\/extreme-barcelona-estrena-mundial-hors-class-uci\\\/\"},\"wordCount\":389,\"publisher\":{\"@id\":\"https:\\\/\\\/extremebarcelona.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/extremebarcelona.com\\\/ca\\\/2026\\\/07\\\/15\\\/extreme-barcelona-estrena-mundial-hors-class-uci\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/extremebarcelona.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/@raimonrg_EXT25_-uci-women-final-2-3-scaled.jpg\",\"keywords\":[\"18\",\"2026\",\"barcelona\",\"bmx\",\"bnx\",\"extreme\",\"urban\"],\"articleSection\":[\"Noticies\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/extremebarcelona.com\\\/ca\\\/2026\\\/07\\\/15\\\/extreme-barcelona-estrena-mundial-hors-class-uci\\\/\",\"url\":\"https:\\\/\\\/extremebarcelona.com\\\/ca\\\/2026\\\/07\\\/15\\\/extreme-barcelona-estrena-mundial-hors-class-uci\\\/\",\"name\":\"Extreme Barcelona far\u00e0 hist\u00f2ria amb l'estrena mundial del nou segell Hors Class de la UCI - Extreme Barcelona\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/extremebarcelona.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/extremebarcelona.com\\\/ca\\\/2026\\\/07\\\/15\\\/extreme-barcelona-estrena-mundial-hors-class-uci\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/extremebarcelona.com\\\/ca\\\/2026\\\/07\\\/15\\\/extreme-barcelona-estrena-mundial-hors-class-uci\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/extremebarcelona.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/@raimonrg_EXT25_-uci-women-final-2-3-scaled.jpg\",\"datePublished\":\"2026-07-15T10:33:49+00:00\",\"description\":\"L'Extreme Barcelona ser\u00e0 el primer esdeveniment del m\u00f3n a estrenar el prestigi\u00f3s segell Hors Class de la UCI per al BMX Freestyle del 4 al 6 de setembre.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/extremebarcelona.com\\\/ca\\\/2026\\\/07\\\/15\\\/extreme-barcelona-estrena-mundial-hors-class-uci\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/extremebarcelona.com\\\/ca\\\/2026\\\/07\\\/15\\\/extreme-barcelona-estrena-mundial-hors-class-uci\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/extremebarcelona.com\\\/ca\\\/2026\\\/07\\\/15\\\/extreme-barcelona-estrena-mundial-hors-class-uci\\\/#primaryimage\",\"url\":\"https:\\\/\\\/extremebarcelona.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/@raimonrg_EXT25_-uci-women-final-2-3-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/extremebarcelona.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/@raimonrg_EXT25_-uci-women-final-2-3-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Extreme Barcelona UCI Hors Class\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/extremebarcelona.com\\\/ca\\\/2026\\\/07\\\/15\\\/extreme-barcelona-estrena-mundial-hors-class-uci\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/extremebarcelona.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Extreme Barcelona far\u00e0 hist\u00f2ria amb l&#8217;estrena mundial del nou segell Hors Class de la UCI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/extremebarcelona.com\\\/#website\",\"url\":\"https:\\\/\\\/extremebarcelona.com\\\/\",\"name\":\"Extreme Barcelona\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/extremebarcelona.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/extremebarcelona.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/extremebarcelona.com\\\/#organization\",\"name\":\"Extreme Barcelona\",\"url\":\"https:\\\/\\\/extremebarcelona.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/extremebarcelona.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/extremebarcelona.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Logo-Extreme-2021.png\",\"contentUrl\":\"https:\\\/\\\/extremebarcelona.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Logo-Extreme-2021.png\",\"width\":500,\"height\":500,\"caption\":\"Extreme Barcelona\"},\"image\":{\"@id\":\"https:\\\/\\\/extremebarcelona.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/extremebarcelona.com\\\/#\\\/schema\\\/person\\\/0ab8e57dd9880fb0b11f077d9f23c4aa\",\"name\":\"Cristian Dedeu Van den Berg\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/41e68b85b7fa9f2110fbebcd69e21f89425478ca6e1e8701732accd271a6b866?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/41e68b85b7fa9f2110fbebcd69e21f89425478ca6e1e8701732accd271a6b866?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/41e68b85b7fa9f2110fbebcd69e21f89425478ca6e1e8701732accd271a6b866?s=96&d=mm&r=g\",\"caption\":\"Cristian Dedeu Van den Berg\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Extreme Barcelona far\u00e0 hist\u00f2ria amb l'estrena mundial del nou segell Hors Class de la UCI - Extreme Barcelona","description":"L'Extreme Barcelona ser\u00e0 el primer esdeveniment del m\u00f3n a estrenar el prestigi\u00f3s segell Hors Class de la UCI per al BMX Freestyle del 4 al 6 de setembre.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/extremebarcelona.com\/ca\/2026\/07\/15\/extreme-barcelona-estrena-mundial-hors-class-uci\/","og_locale":"ca_ES","og_type":"article","og_title":"Extreme Barcelona far\u00e0 hist\u00f2ria amb l'estrena mundial del nou segell Hors Class de la UCI - Extreme Barcelona","og_description":"L'Extreme Barcelona ser\u00e0 el primer esdeveniment del m\u00f3n a estrenar el prestigi\u00f3s segell Hors Class de la UCI per al BMX Freestyle del 4 al 6 de setembre.","og_url":"https:\/\/extremebarcelona.com\/ca\/2026\/07\/15\/extreme-barcelona-estrena-mundial-hors-class-uci\/","og_site_name":"Extreme Barcelona","article_published_time":"2026-07-15T10:33:49+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/extremebarcelona.com\/wp-content\/uploads\/2026\/07\/@raimonrg_EXT25_-uci-women-final-2-3-scaled.jpg","type":"image\/jpeg"}],"author":"Cristian Dedeu Van den Berg","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"Cristian Dedeu Van den Berg","Temps estimat de lectura":"2 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/extremebarcelona.com\/ca\/2026\/07\/15\/extreme-barcelona-estrena-mundial-hors-class-uci\/#article","isPartOf":{"@id":"https:\/\/extremebarcelona.com\/ca\/2026\/07\/15\/extreme-barcelona-estrena-mundial-hors-class-uci\/"},"author":{"name":"Cristian Dedeu Van den Berg","@id":"https:\/\/extremebarcelona.com\/#\/schema\/person\/0ab8e57dd9880fb0b11f077d9f23c4aa"},"headline":"Extreme Barcelona far\u00e0 hist\u00f2ria amb l&#8217;estrena mundial del nou segell Hors Class de la UCI","datePublished":"2026-07-15T10:33:49+00:00","mainEntityOfPage":{"@id":"https:\/\/extremebarcelona.com\/ca\/2026\/07\/15\/extreme-barcelona-estrena-mundial-hors-class-uci\/"},"wordCount":389,"publisher":{"@id":"https:\/\/extremebarcelona.com\/#organization"},"image":{"@id":"https:\/\/extremebarcelona.com\/ca\/2026\/07\/15\/extreme-barcelona-estrena-mundial-hors-class-uci\/#primaryimage"},"thumbnailUrl":"https:\/\/extremebarcelona.com\/wp-content\/uploads\/2026\/07\/@raimonrg_EXT25_-uci-women-final-2-3-scaled.jpg","keywords":["18","2026","barcelona","bmx","bnx","extreme","urban"],"articleSection":["Noticies"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/extremebarcelona.com\/ca\/2026\/07\/15\/extreme-barcelona-estrena-mundial-hors-class-uci\/","url":"https:\/\/extremebarcelona.com\/ca\/2026\/07\/15\/extreme-barcelona-estrena-mundial-hors-class-uci\/","name":"Extreme Barcelona far\u00e0 hist\u00f2ria amb l'estrena mundial del nou segell Hors Class de la UCI - Extreme Barcelona","isPartOf":{"@id":"https:\/\/extremebarcelona.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/extremebarcelona.com\/ca\/2026\/07\/15\/extreme-barcelona-estrena-mundial-hors-class-uci\/#primaryimage"},"image":{"@id":"https:\/\/extremebarcelona.com\/ca\/2026\/07\/15\/extreme-barcelona-estrena-mundial-hors-class-uci\/#primaryimage"},"thumbnailUrl":"https:\/\/extremebarcelona.com\/wp-content\/uploads\/2026\/07\/@raimonrg_EXT25_-uci-women-final-2-3-scaled.jpg","datePublished":"2026-07-15T10:33:49+00:00","description":"L'Extreme Barcelona ser\u00e0 el primer esdeveniment del m\u00f3n a estrenar el prestigi\u00f3s segell Hors Class de la UCI per al BMX Freestyle del 4 al 6 de setembre.","breadcrumb":{"@id":"https:\/\/extremebarcelona.com\/ca\/2026\/07\/15\/extreme-barcelona-estrena-mundial-hors-class-uci\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/extremebarcelona.com\/ca\/2026\/07\/15\/extreme-barcelona-estrena-mundial-hors-class-uci\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/extremebarcelona.com\/ca\/2026\/07\/15\/extreme-barcelona-estrena-mundial-hors-class-uci\/#primaryimage","url":"https:\/\/extremebarcelona.com\/wp-content\/uploads\/2026\/07\/@raimonrg_EXT25_-uci-women-final-2-3-scaled.jpg","contentUrl":"https:\/\/extremebarcelona.com\/wp-content\/uploads\/2026\/07\/@raimonrg_EXT25_-uci-women-final-2-3-scaled.jpg","width":2560,"height":1707,"caption":"Extreme Barcelona UCI Hors Class"},{"@type":"BreadcrumbList","@id":"https:\/\/extremebarcelona.com\/ca\/2026\/07\/15\/extreme-barcelona-estrena-mundial-hors-class-uci\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/extremebarcelona.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Extreme Barcelona far\u00e0 hist\u00f2ria amb l&#8217;estrena mundial del nou segell Hors Class de la UCI"}]},{"@type":"WebSite","@id":"https:\/\/extremebarcelona.com\/#website","url":"https:\/\/extremebarcelona.com\/","name":"Extreme Barcelona","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/extremebarcelona.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/extremebarcelona.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/extremebarcelona.com\/#organization","name":"Extreme Barcelona","url":"https:\/\/extremebarcelona.com\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/extremebarcelona.com\/#\/schema\/logo\/image\/","url":"https:\/\/extremebarcelona.com\/wp-content\/uploads\/2021\/04\/Logo-Extreme-2021.png","contentUrl":"https:\/\/extremebarcelona.com\/wp-content\/uploads\/2021\/04\/Logo-Extreme-2021.png","width":500,"height":500,"caption":"Extreme Barcelona"},"image":{"@id":"https:\/\/extremebarcelona.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/extremebarcelona.com\/#\/schema\/person\/0ab8e57dd9880fb0b11f077d9f23c4aa","name":"Cristian Dedeu Van den Berg","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/41e68b85b7fa9f2110fbebcd69e21f89425478ca6e1e8701732accd271a6b866?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/41e68b85b7fa9f2110fbebcd69e21f89425478ca6e1e8701732accd271a6b866?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/41e68b85b7fa9f2110fbebcd69e21f89425478ca6e1e8701732accd271a6b866?s=96&d=mm&r=g","caption":"Cristian Dedeu Van den Berg"}}]}},"_links":{"self":[{"href":"https:\/\/extremebarcelona.com\/ca\/wp-json\/wp\/v2\/posts\/28105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/extremebarcelona.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/extremebarcelona.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/extremebarcelona.com\/ca\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/extremebarcelona.com\/ca\/wp-json\/wp\/v2\/comments?post=28105"}],"version-history":[{"count":1,"href":"https:\/\/extremebarcelona.com\/ca\/wp-json\/wp\/v2\/posts\/28105\/revisions"}],"predecessor-version":[{"id":28106,"href":"https:\/\/extremebarcelona.com\/ca\/wp-json\/wp\/v2\/posts\/28105\/revisions\/28106"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/extremebarcelona.com\/ca\/wp-json\/wp\/v2\/media\/28082"}],"wp:attachment":[{"href":"https:\/\/extremebarcelona.com\/ca\/wp-json\/wp\/v2\/media?parent=28105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/extremebarcelona.com\/ca\/wp-json\/wp\/v2\/categories?post=28105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/extremebarcelona.com\/ca\/wp-json\/wp\/v2\/tags?post=28105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}